{"id":52410,"date":"2024-10-08T11:56:07","date_gmt":"2024-10-08T11:56:07","guid":{"rendered":"https:\/\/decabaturisme.com\/dcb-serveis\/creacio-producte-turistic\/"},"modified":"2024-12-21T11:26:21","modified_gmt":"2024-12-21T11:26:21","slug":"creacion-producto-turistico","status":"publish","type":"page","link":"https:\/\/decabaturisme.com\/es\/servicios\/creacion-producto-turistico\/","title":{"rendered":"Creaci\u00f3n de producto tur\u00edstico"},"content":{"rendered":"\n\t<section class=\"section\" id=\"section_1086692921\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-888438596\">\n\n\t<div id=\"col-1441957939\" class=\"col small-12 large-12\"  data-animate=\"fadeInRight\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row align-center\"  id=\"row-327806051\">\n\n\t<div id=\"col-1843399471\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"nav-wrapper\"><ul class=\"nav nav-uppercase nav-horizontal nav-size-xsmall nav-outline text-center nav-center\"><p class=\"lead shortcode-error text-center\">Sorry, no pages was found<\/p><\/ul><\/div>\n\t<div id=\"gap-1606769470\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1606769470 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<h1>CREACI\u00d3N DE PRODUCTO TUR\u00cdSTICO<\/h1>\n<div class=\"is-divider divider clearfix\" style=\"max-width:50px;background-color:rgb(168, 10, 67);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<h3>Dise\u00f1o de productos tur\u00edsticos singulares<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-middle align-center\"  id=\"row-2059067191\">\n\n\t<div id=\"col-81450958\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:2px 2px 2px 2px;margin:-5px 0px -5px 0px;\">\n\t<\/div>\n\t\t\t\n\t<div id=\"ux-lottie-3160669657\" class=\"ux-lottie\" >\n\t\t\t\t<lottie-player class=\"ux-lottie__player\" data-params=\"{&quot;src&quot;:&quot;https:\\\/\\\/decabaturisme.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/muntanyes-globus.json&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:false,&quot;controls&quot;:false,&quot;speed&quot;:&quot;1&quot;,&quot;direction&quot;:1,&quot;trigger&quot;:&quot;click&quot;,&quot;mouseout&quot;:&quot;&quot;,&quot;start&quot;:0,&quot;end&quot;:100,&quot;scrollActionType&quot;:&quot;seek&quot;,&quot;visibilityStart&quot;:0,&quot;visibilityEnd&quot;:100,&quot;id&quot;:&quot;ux-lottie-3160669657&quot;}\" ><\/lottie-player>\n\t\t\t\t\n<style>\n#ux-lottie-3160669657 {\n  width: 100%;\n  height: 125px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-228063559\" class=\"col medium-8 small-12 large-8\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: justify;\">La creciente demanda de experiencias aut\u00e9nticas y personalizadas hace imprescindible que territorios y empresas ofrezcan <span style=\"color: #a80a43;\"><strong>productos tur\u00edsticos bien estructurados y competitivos<\/strong><\/span>. En <span style=\"color: #a80a43;\"><strong><em>DECABA Turisme<\/em><\/strong><\/span>, acompa\u00f1amos a los destinos en cada fase del proceso de creaci\u00f3n de productos tur\u00edsticos especializados y segmentados.<\/p>\n<p>Trabajamos para que vuestra oferta sea atractiva y diferenciada, con un enfoque sostenible e innovador:<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1878117533\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<ul>\n<li><strong><span style=\"color: #a80a43;\">Evaluaci\u00f3n de tendencias<\/span><\/strong>, necesidades de los mercados emisores y an\u00e1lisis de la competencia.<\/li>\n<li><strong><span style=\"color: #a80a43;\">Dise\u00f1o de experiencias tur\u00edsticas sostenibles<\/span><\/strong> basadas en los recursos propios del territorio.<\/li>\n<li><strong><span style=\"color: #a80a43;\">Segmentaci\u00f3n de la oferta<\/span><\/strong> seg\u00fan el p\u00fablico objetivo.<\/li>\n<li><strong><span style=\"color: #a80a43;\">Coordinaci\u00f3n entre destinos<\/span><\/strong> para crear productos tur\u00edsticos comunes.<\/li>\n<li><strong><span style=\"color: #a80a43;\">Creaci\u00f3n de fichas y dossiers<\/span><\/strong> de productos tur\u00edsticos.<\/li>\n<li><strong><span style=\"color: #a80a43;\">Elaboraci\u00f3n de manuales de buenas pr\u00e1cticas<\/span><\/strong> para el desarrollo de productos tur\u00edsticos.<\/li>\n<li><strong><span style=\"color: #a80a43;\">Dise\u00f1o de Planes de comunicaci\u00f3n<\/span><\/strong> y portafolios para dar a conocer y comercializar el producto en los mercados.<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-211996877\" class=\"col medium-5 small-11 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover img-berto-radius x md-x lg-x y md-y lg-y\" id=\"image_1075860877\">\n\t\t\t\t\t\t<div data-animate=\"flipInY\">\t\t<div class=\"img-inner image-grayscale box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/10\/Pla-Estrategic-Santa-Pau-lores.jpg\" class=\"attachment-large size-large\" alt=\"Presentaci\u00f3 Santa Pau\" srcset=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/10\/Pla-Estrategic-Santa-Pau-lores.jpg 640w, https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/10\/Pla-Estrategic-Santa-Pau-lores-533x400.jpg 533w, https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/10\/Pla-Estrategic-Santa-Pau-lores-600x450.jpg 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_1075860877 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-541350204\" class=\"col medium-11 large-12\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"text-align: justify;\">En <span style=\"color: #a80a43;\"><em><strong>DECABA Turisme<\/strong><\/em><\/span>, te ayudamos a transformar los recursos del territorio en experiencias \u00fanicas que capten la atenci\u00f3n de los viajeros de hoy y del futuro.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row align-center\"  id=\"row-1657350469\">\n\n\t<div id=\"col-1714507595\" class=\"col small-12 large-12\"  data-animate=\"fadeInRight\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2>Proyectos asociados<\/h2>\n<div class=\"is-divider divider clearfix\" style=\"max-width:50px;background-color:rgb(168, 10, 67);\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1657350469 > .col > .col-inner {\n  padding: 50px 10px 0px 10px;\n}\n@media (min-width:850px) {\n  #row-1657350469 > .col > .col-inner {\n    padding: 50px 0px 0px 0px;\n  }\n}\n<\/style>\n<\/div>\n\n  \n    <div class=\"row large-columns-1 medium-columns-1 small-columns-1\" >\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"border-radius:5%;width:32%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/decabaturisme.com\/es\/creacion-manual-producto-cork-experience\/\" class=\"plain\" aria-label=\"Creaci\u00f3n del Manual de Producto \u201cCork Experience\u201d\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2024\/10\/Cork-Experience-lores.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Cork Experience\" srcset=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2024\/10\/Cork-Experience-lores.jpg 640w, https:\/\/decabaturisme.com\/wp-content\/uploads\/2024\/10\/Cork-Experience-lores-600x338.jpg 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large uppercase\">\n\t\t\t\t\t\t<a href=\"https:\/\/decabaturisme.com\/es\/creacion-manual-producto-cork-experience\/\" class=\"plain\">Creaci\u00f3n del Manual de Producto \u201cCork Experience\u201d<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">octubre 2024<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt show-on-hover hover-fade\">\n\t\t\t\t\t\tRevisi\u00f3n del Manual de Creaci\u00f3n de Producto de la red Retecork junto con la redacci\u00f3n de un protocolo para el dise\u00f1o de nuevo producto sostenible y un modelo de fichas [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"border-radius:5%;width:32%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/decabaturisme.com\/es\/creacion-producto-turistico-palau-solita-plegamans\/\" class=\"plain\" aria-label=\"Creaci\u00f3n de producto tur\u00edstico para el municipio de Palau Solit\u00e0 i Plegamans.\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"533\" height=\"400\" src=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2024\/01\/santa-maria-palau-solita-plegamans640x480-533x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"Esgl\u00e9sia rom\u00e0nica de Santa M\u00aa de Palau-Solit\u00e0 i Plegamans\" srcset=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2024\/01\/santa-maria-palau-solita-plegamans640x480-533x400.jpg 533w, https:\/\/decabaturisme.com\/wp-content\/uploads\/2024\/01\/santa-maria-palau-solita-plegamans640x480-600x450.jpg 600w, https:\/\/decabaturisme.com\/wp-content\/uploads\/2024\/01\/santa-maria-palau-solita-plegamans640x480.jpg 640w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large uppercase\">\n\t\t\t\t\t\t<a href=\"https:\/\/decabaturisme.com\/es\/creacion-producto-turistico-palau-solita-plegamans\/\" class=\"plain\">Creaci\u00f3n de producto tur\u00edstico para el municipio de Palau Solit\u00e0 i Plegamans.<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">enero 2024<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt show-on-hover hover-fade\">\n\t\t\t\t\t\tDise\u00f1o de tres rutas con visita guiada sobre la base del patrimonio medieval y cultural del municipio. Se incorpora el Plan de Comunicaci\u00f3n para la difusi\u00f3n de las rutas.\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-vertical box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" style=\"border-radius:5%;width:32%;\">\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:56%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/decabaturisme.com\/es\/consolidacion-productos-turisticos-pallars-jussa-post-covid-19\/\" class=\"plain\" aria-label=\"Consolidaci\u00f3n de productos tur\u00edsticos del Pallars Juss\u00e0 y adaptaci\u00f3n de la oferta como respuesta a las nuevas tendencias post Covid-19.\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"443\" height=\"400\" src=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/10\/Producte-turistc-Pallars-Jussa-lowres-443x400.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" srcset=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/10\/Producte-turistc-Pallars-Jussa-lowres-443x400.jpg 443w, https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/10\/Producte-turistc-Pallars-Jussa-lowres-600x542.jpg 600w, https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/10\/Producte-turistc-Pallars-Jussa-lowres.jpg 640w\" sizes=\"(max-width: 443px) 100vw, 443px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large uppercase\">\n\t\t\t\t\t\t<a href=\"https:\/\/decabaturisme.com\/es\/consolidacion-productos-turisticos-pallars-jussa-post-covid-19\/\" class=\"plain\">Consolidaci\u00f3n de productos tur\u00edsticos del Pallars Juss\u00e0 y adaptaci\u00f3n de la oferta como respuesta a las nuevas tendencias post Covid-19.<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t<div class=\"post-meta is-small op-8\">noviembre 2022<\/div>\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt show-on-hover hover-fade\">\n\t\t\t\t\t\tEstudio de mercado y acciones de apoyo y acompa\u00f1amiento a las empresas para dotar de herramientas a los agentes de la comarca para hacer frente a los cambios post Covid [...]\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1086692921 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":52409,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-52410","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/pages\/52410"}],"collection":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/comments?post=52410"}],"version-history":[{"count":10,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/pages\/52410\/revisions"}],"predecessor-version":[{"id":54058,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/pages\/52410\/revisions\/54058"}],"up":[{"embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/pages\/52409"}],"wp:attachment":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/media?parent=52410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}