{"id":54069,"date":"2023-07-19T10:39:03","date_gmt":"2023-07-19T10:39:03","guid":{"rendered":"https:\/\/decabaturisme.com\/assistencia-tecnica-dinamitzacio-edifici-abadia-senan\/"},"modified":"2024-12-21T12:15:19","modified_gmt":"2024-12-21T12:15:19","slug":"asistencia-tecnica-dinamizacion-edificio-abadia-senan","status":"publish","type":"post","link":"https:\/\/decabaturisme.com\/es\/asistencia-tecnica-dinamizacion-edificio-abadia-senan\/","title":{"rendered":"Asistencia t\u00e9cnica para la dinamizaci\u00f3n del edificio de la abad\u00eda de Senan"},"content":{"rendered":"<p>Colaboraci\u00f3n con el Ayuntamiento de Senan para ofrecer asistencia t\u00e9cnica para la dinamizaci\u00f3n de la Abad\u00eda de Senan, un edificio recientemente rehabilitado en la Conca de Barber\u00e0.<\/p>\n<div class=\"row align-center\"  id=\"row-867036292\">\n\n\t<div id=\"col-386993877\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_427925790\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/07\/abadia-senan-lores.jpg\" class=\"attachment-large size-large\" alt=\"Abadia de Senan\" srcset=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/07\/abadia-senan-lores.jpg 640w, https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/07\/abadia-senan-lores-533x400.jpg 533w, https:\/\/decabaturisme.com\/wp-content\/uploads\/2023\/07\/abadia-senan-lores-600x450.jpg 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_427925790 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p>Esta iniciativa tiene como objetivo posicionar la abad\u00eda como un espacio multifuncional, capaz de acoger estancias, eventos culturales, art\u00edsticos y empresariales, a la vez que se convierte en un punto de encuentro para la comunidad local.<\/p>\n<p>Las acciones incluyen reuniones con agentes clave, apoyo en la creaci\u00f3n de contenidos y materiales de difusi\u00f3n, identificaci\u00f3n de colaboradores y prescriptores, y b\u00fasqueda de financiaci\u00f3n para futuros proyectos.<\/p>\n<p>A trav\u00e9s de esta colaboraci\u00f3n, se busca fomentar el patrimonio, la cultura y el desarrollo local de Senan y su entorno.<\/p>\n<p>Julio \u2013 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acompa\u00f1amiento al ayuntamiento de Senan para hacer posible dar a conocer la Abad\u00eda de Senan como sede de alojamiento empresarial, favorecer estancias y organizar eventos.<\/p>\n","protected":false},"author":1,"featured_media":53470,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[413],"tags":[],"class_list":["post-54069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-secretarias-tecnicas"],"_links":{"self":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/posts\/54069"}],"collection":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/comments?post=54069"}],"version-history":[{"count":3,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/posts\/54069\/revisions"}],"predecessor-version":[{"id":54137,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/posts\/54069\/revisions\/54137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/media\/53470"}],"wp:attachment":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/media?parent=54069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/categories?post=54069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/tags?post=54069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}