{"id":54142,"date":"2022-10-01T10:43:27","date_gmt":"2022-10-01T10:43:27","guid":{"rendered":"https:\/\/decabaturisme.com\/asistencia-tecnica-a-la-preparacio-dun-projecte-de-planes-de-sostenibilidad-turistica-en-destinos-per-a-la-comarca-de-lalt-emporda\/"},"modified":"2024-12-21T12:30:43","modified_gmt":"2024-12-21T12:30:43","slug":"asistencia-tecnica-proyecto-sostenibilidad-turistica-comarca-alt-emporda","status":"publish","type":"post","link":"https:\/\/decabaturisme.com\/es\/asistencia-tecnica-proyecto-sostenibilidad-turistica-comarca-alt-emporda\/","title":{"rendered":"Asistencia t\u00e9cnica para la preparaci\u00f3n de un proyecto de Planes de Sostenibilidad Tur\u00edstica en Destinos para la comarca del Alt Empord\u00e0."},"content":{"rendered":"<p><em><strong>DECABA Turisme<\/strong><\/em> ha colaborado con el Consell Comarcal del Alt Empord\u00e0 en la redacci\u00f3n del proyecto presentado a la convocatoria de Planes de Sostenibilidad Tur\u00edstica en Destinos.<\/p>\n<div class=\"row align-center\"  id=\"row-1897056816\">\n\n\t<div id=\"col-1307581494\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_877138112\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner box-shadow-3 dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2022\/10\/alt-emporda-sant-miquel-bassegoda-lores.jpg\" class=\"attachment-large size-large\" alt=\"Esgl\u00e9sia de Sant Miquel de Bassegoda (Alt Empord\u00e0)\" srcset=\"https:\/\/decabaturisme.com\/wp-content\/uploads\/2022\/10\/alt-emporda-sant-miquel-bassegoda-lores.jpg 640w, https:\/\/decabaturisme.com\/wp-content\/uploads\/2022\/10\/alt-emporda-sant-miquel-bassegoda-lores-533x400.jpg 533w, https:\/\/decabaturisme.com\/wp-content\/uploads\/2022\/10\/alt-emporda-sant-miquel-bassegoda-lores-600x450.jpg 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_877138112 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p>Esta iniciativa plantea un modelo tur\u00edstico sostenible que conecte la costa con el interior, con el objetivo de desestacionalizar la actividad tur\u00edstica y diversificar la oferta.<\/p>\n<p>El proyecto incluye acciones orientadas a valorar el patrimonio natural y cultural, promover la movilidad sostenible y fomentar la creaci\u00f3n de nuevas experiencias tur\u00edsticas.<\/p>\n<p>La elaboraci\u00f3n de la memoria ha supuesto un trabajo de conceptualizaci\u00f3n, recogida de informaci\u00f3n y definici\u00f3n de una estrategia clara que ponga en valor el potencial tur\u00edstico de la comarca.<\/p>\n<p>Octubre \u2013 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acompa\u00f1amiento al Consejo Comarcal del Alt Empord\u00e0 para la redacci\u00f3n de un proyecto comarcal para presentarlo en la convocatoria de PSTD.<\/p>\n","protected":false},"author":1,"featured_media":53490,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[413],"tags":[],"class_list":["post-54142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-secretarias-tecnicas"],"_links":{"self":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/posts\/54142"}],"collection":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/comments?post=54142"}],"version-history":[{"count":3,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/posts\/54142\/revisions"}],"predecessor-version":[{"id":54174,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/posts\/54142\/revisions\/54174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/media\/53490"}],"wp:attachment":[{"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/media?parent=54142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/categories?post=54142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decabaturisme.com\/es\/wp-json\/wp\/v2\/tags?post=54142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}